{"id":31328,"date":"2022-06-09T19:42:44","date_gmt":"2022-06-09T23:42:44","guid":{"rendered":"https:\/\/buffalogolfer.com\/wordpress\/?p=31328"},"modified":"2022-06-09T19:44:00","modified_gmt":"2022-06-09T23:44:00","slug":"eve-of-the-curtis-cup-photo-gallery","status":"publish","type":"post","link":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/","title":{"rendered":"Eve of the Curtis Cup: Photo Gallery"},"content":{"rendered":"<p>I promise that I&#8217;ll have some course and competition photos tomorrow. For now, here are some looks from the Opening Ceremony, held Thursday evening.<\/p>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">This slideshow requires JavaScript.<\/p><div id=\"gallery-31328-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6464-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31329&quot;,&quot;title&quot;:&quot;IMG_6464 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6456-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31330&quot;,&quot;title&quot;:&quot;IMG_6456 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6458-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31331&quot;,&quot;title&quot;:&quot;IMG_6458 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6457-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31332&quot;,&quot;title&quot;:&quot;IMG_6457 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6460-Small.jpg?fit=640%2C480\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31333&quot;,&quot;title&quot;:&quot;IMG_6460 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6461-Small.jpg?fit=640%2C480\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31334&quot;,&quot;title&quot;:&quot;IMG_6461 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6459-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31335&quot;,&quot;title&quot;:&quot;IMG_6459 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6463-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31336&quot;,&quot;title&quot;:&quot;IMG_6463 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6465-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31337&quot;,&quot;title&quot;:&quot;IMG_6465 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6171-Small.jpg?fit=720%2C480\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31338&quot;,&quot;title&quot;:&quot;IMG_6171 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6193-Small.jpg?fit=720%2C480\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31339&quot;,&quot;title&quot;:&quot;IMG_6193 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6494-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31340&quot;,&quot;title&quot;:&quot;IMG_6494 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6495-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31341&quot;,&quot;title&quot;:&quot;IMG_6495 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6496-Small-rotated.jpg?fit=480%2C640\\u0026ssl=1&quot;,&quot;id&quot;:&quot;31342&quot;,&quot;title&quot;:&quot;IMG_6496 (Small)&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>I promise that I&#8217;ll have some course and competition photos tomorrow. For now, here are some looks from the Opening Ceremony, held Thursday evening.<\/p>\n","protected":false},"author":1,"featured_media":31335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[1795,1771],"class_list":["post-31328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mo-golf","tag-2022-curtis-cup","tag-merion-golf-club"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eve of the Curtis Cup: Photo Gallery &#062; BuffaloGolfer.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eve of the Curtis Cup: Photo Gallery &#062; BuffaloGolfer.com\" \/>\n<meta property=\"og:description\" content=\"I promise that I&#8217;ll have some course and competition photos tomorrow. For now, here are some looks from the Opening Ceremony, held Thursday evening.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"BuffaloGolfer.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BuffaloGolferCom-54172563134\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T23:42:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-09T23:44:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2022\/06\/IMG_6459-Small-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mo&#039;Golf\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mo&#039;Golf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/\"},\"author\":{\"name\":\"Mo'Golf\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/d008e5b529360acedbc8ee2aa899d6de\"},\"headline\":\"Eve of the Curtis Cup: Photo Gallery\",\"datePublished\":\"2022-06-09T23:42:44+00:00\",\"dateModified\":\"2022-06-09T23:44:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/\"},\"wordCount\":38,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1\",\"keywords\":[\"2022 Curtis Cup\",\"Merion Golf Club\"],\"articleSection\":[\"Mo' Golf\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/\",\"url\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/\",\"name\":\"Eve of the Curtis Cup: Photo Gallery &#062; BuffaloGolfer.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1\",\"datePublished\":\"2022-06-09T23:42:44+00:00\",\"dateModified\":\"2022-06-09T23:44:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1\",\"width\":480,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/eve-of-the-curtis-cup-photo-gallery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eve of the Curtis Cup: Photo Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/\",\"name\":\"BuffaloGolfer.com\",\"description\":\"The guide to golf in Buffalo-Niagara\",\"publisher\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#organization\",\"name\":\"BuffaloGolfer\",\"url\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/BuffaloGolferForBDGA20232024-Medium.png?fit=922%2C768&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/BuffaloGolferForBDGA20232024-Medium.png?fit=922%2C768&ssl=1\",\"width\":922,\"height\":768,\"caption\":\"BuffaloGolfer\"},\"image\":{\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BuffaloGolferCom-54172563134\\\/\",\"https:\\\/\\\/x.com\\\/buffalogolfer\",\"https:\\\/\\\/www.instagram.com\\\/buffalogolfer\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/d008e5b529360acedbc8ee2aa899d6de\",\"name\":\"Mo'Golf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/caricature_small.png?fit=76%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/caricature_small.png?fit=76%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/buffalogolfer.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/caricature_small.png?fit=76%2C96&ssl=1\",\"caption\":\"Mo'Golf\"},\"url\":\"https:\\\/\\\/buffalogolfer.com\\\/wordpress\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eve of the Curtis Cup: Photo Gallery &#062; BuffaloGolfer.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/","og_locale":"en_US","og_type":"article","og_title":"Eve of the Curtis Cup: Photo Gallery &#062; BuffaloGolfer.com","og_description":"I promise that I&#8217;ll have some course and competition photos tomorrow. For now, here are some looks from the Opening Ceremony, held Thursday evening.","og_url":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/","og_site_name":"BuffaloGolfer.com","article_publisher":"https:\/\/www.facebook.com\/BuffaloGolferCom-54172563134\/","article_published_time":"2022-06-09T23:42:44+00:00","article_modified_time":"2022-06-09T23:44:00+00:00","og_image":[{"width":480,"height":640,"url":"http:\/\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2022\/06\/IMG_6459-Small-rotated.jpg","type":"image\/jpeg"}],"author":"Mo'Golf","twitter_misc":{"Written by":"Mo'Golf","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/#article","isPartOf":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/"},"author":{"name":"Mo'Golf","@id":"https:\/\/buffalogolfer.com\/wordpress\/#\/schema\/person\/d008e5b529360acedbc8ee2aa899d6de"},"headline":"Eve of the Curtis Cup: Photo Gallery","datePublished":"2022-06-09T23:42:44+00:00","dateModified":"2022-06-09T23:44:00+00:00","mainEntityOfPage":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/"},"wordCount":38,"commentCount":0,"publisher":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/#organization"},"image":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2022\/06\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1","keywords":["2022 Curtis Cup","Merion Golf Club"],"articleSection":["Mo' Golf"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/","url":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/","name":"Eve of the Curtis Cup: Photo Gallery &#062; BuffaloGolfer.com","isPartOf":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/#primaryimage"},"image":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2022\/06\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1","datePublished":"2022-06-09T23:42:44+00:00","dateModified":"2022-06-09T23:44:00+00:00","breadcrumb":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/#primaryimage","url":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2022\/06\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1","contentUrl":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2022\/06\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1","width":480,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/buffalogolfer.com\/wordpress\/eve-of-the-curtis-cup-photo-gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/buffalogolfer.com\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Eve of the Curtis Cup: Photo Gallery"}]},{"@type":"WebSite","@id":"https:\/\/buffalogolfer.com\/wordpress\/#website","url":"https:\/\/buffalogolfer.com\/wordpress\/","name":"BuffaloGolfer.com","description":"The guide to golf in Buffalo-Niagara","publisher":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/buffalogolfer.com\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/buffalogolfer.com\/wordpress\/#organization","name":"BuffaloGolfer","url":"https:\/\/buffalogolfer.com\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/buffalogolfer.com\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2023\/08\/BuffaloGolferForBDGA20232024-Medium.png?fit=922%2C768&ssl=1","contentUrl":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2023\/08\/BuffaloGolferForBDGA20232024-Medium.png?fit=922%2C768&ssl=1","width":922,"height":768,"caption":"BuffaloGolfer"},"image":{"@id":"https:\/\/buffalogolfer.com\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BuffaloGolferCom-54172563134\/","https:\/\/x.com\/buffalogolfer","https:\/\/www.instagram.com\/buffalogolfer\/"]},{"@type":"Person","@id":"https:\/\/buffalogolfer.com\/wordpress\/#\/schema\/person\/d008e5b529360acedbc8ee2aa899d6de","name":"Mo'Golf","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2016\/01\/caricature_small.png?fit=76%2C96&ssl=1","url":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2016\/01\/caricature_small.png?fit=76%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2016\/01\/caricature_small.png?fit=76%2C96&ssl=1","caption":"Mo'Golf"},"url":"https:\/\/buffalogolfer.com\/wordpress\/author\/admin\/"}]}},"views":2549,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/buffalogolfer.com\/wordpress\/wp-content\/uploads\/2022\/06\/IMG_6459-Small-rotated.jpg?fit=480%2C640&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p20nYT-89i","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/posts\/31328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/comments?post=31328"}],"version-history":[{"count":1,"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/posts\/31328\/revisions"}],"predecessor-version":[{"id":31343,"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/posts\/31328\/revisions\/31343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/media\/31335"}],"wp:attachment":[{"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/media?parent=31328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/categories?post=31328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buffalogolfer.com\/wordpress\/wp-json\/wp\/v2\/tags?post=31328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}